{"id":669,"date":"2018-06-05T10:17:38","date_gmt":"2018-06-05T08:17:38","guid":{"rendered":"http:\/\/10.0.80.84\/devLaLigue53\/public\/wordpress-4.9.6-fr_FR\/wordpress\/?p=669"},"modified":"2018-06-13T12:16:57","modified_gmt":"2018-06-13T10:16:57","slug":"formation-des-delegues-eleves","status":"publish","type":"post","link":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/","title":{"rendered":"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves"},"content":{"rendered":"<h3><\/h3>\n<p>Nous consid\u00e9rons que former les d\u00e9l\u00e9gu\u00e9s \u00e9l\u00e8ves comporte un double enjeu citoyen dans les coll\u00e8ges et les lyc\u00e9es :<\/p>\n<ul>\n<li>Permettre aux d\u00e9l\u00e9gu\u00e9s d&rsquo;exercer au mieux leur fonction par une meilleure connaissance de leur \u00e9tablissement et de leur r\u00f4le<\/li>\n<li>Pour l&rsquo;\u00e9tablissement, c&rsquo;est un temps qui permet d&rsquo;expliciter le r\u00f4le des d\u00e9l\u00e9gu\u00e9s, d&rsquo;informer sur la vie et le fonctionnement de l&rsquo;\u00e9tablissement, de favoriser le dialogue entre tous les acteurs de la vie scolaire<\/li>\n<\/ul>\n<p align=\"center\">\u00a0<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-552\" src=\"http:\/\/dev.laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg 300w, https:\/\/laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-768x576.jpg 768w, https:\/\/laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-1024x768.jpg 1024w, https:\/\/laligue53.org\/wp-content\/uploads\/2018\/06\/delegue.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3><\/h3>\n<h3 class=\"titre-blue\">Pour qui ?<\/h3>\n<p>\u00c9coles, coll\u00e8ges, lyc\u00e9es.<\/p>\n<p>Instances Lyc\u00e9ennes : CVL, FSE, Maison de Lyc\u00e9ens, Conseils d&rsquo;Administration<\/p>\n<h3 class=\"titre-blue\">Objectifs<\/h3>\n<p>La Ligue propose des modules de formation adapt\u00e9s aux besoins identifi\u00e9s par les \u00e9quipes \u00e9ducatives :<\/p>\n<ul>\n<li>Permettre aux d\u00e9l\u00e9gu\u00e9s de conna\u00eetre leurs devoirs et leurs droits afin de pouvoir les exercer<\/li>\n<li>D\u00e9velopper des capacit\u00e9s et des comp\u00e9tences \u00e0 la vie d\u00e9mocratique par l&rsquo;exp\u00e9rience de la participation et de la prise de responsabilit\u00e9<\/li>\n<li>Pr\u00e9parer les d\u00e9l\u00e9gu\u00e9s \u00e0 l&rsquo;exercice de leur mandat d&rsquo;\u00e9lu, aux fonctions de repr\u00e9sentation, de communication et d&rsquo;animation<\/li>\n<li>Permettre \u00e0 l&rsquo;adulte d&rsquo;accompagner le d\u00e9l\u00e9gu\u00e9 \u00e9l\u00e8ve dans sa mission<\/li>\n<\/ul>\n<p>NOUS VOUS PROPOSONS : Rencontre et pr\u00e9paration avec vous de l&rsquo;intervention, des contenus et objectifs adapt\u00e9s au groupe d&rsquo;\u00e9l\u00e8ves.<\/p>\n<p>Intervention en petit groupe pour une formation allant de 2 journ\u00e9es jusqu&rsquo;\u00e0 des modules de trois jours au cours de l&rsquo;ann\u00e9e par un ou des formateurs FAL sp\u00e9cialement form\u00e9s pour intervenir aupr\u00e8s des scolaires.<\/p>\n<h3 class=\"titre-blue\">Apport p\u00e9dagogique<\/h3>\n<p>Nous pouvons mobiliser notre \u00e9quipe p\u00e9dagogique tout au long de l&rsquo;ann\u00e9e avec des temps de formation sp\u00e9cifiques pour les enseignants en d\u00e9but d&rsquo;ann\u00e9e.<br \/>\nTechniques et m\u00e9thodes p\u00e9dagogiques actives qui favorisent la prise de parole des jeunes (jeux, \u00e9changes, mises en situation&#8230;)<\/p>\n<p>Co\u00fbt de la formation : nous consulter<\/p>\n<p><a href=\"http:\/\/www.laliguepdl.org\/fr\/component\/contact\/contact\/12-la-ligue-des-pays-de-la-loire\/3-coordination-education\">Vous pouvez nous contacter pour vous en savoir plus sur nos propositions de de formation<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous consid\u00e9rons que former les d\u00e9l\u00e9gu\u00e9s \u00e9l\u00e8ves comporte un double enjeu citoyen dans les coll\u00e8ges et les lyc\u00e9es : Permettre aux d\u00e9l\u00e9gu\u00e9s d&rsquo;exercer au mieux leur fonction par une meilleure connaissance de leur \u00e9tablissement et de leur r\u00f4le Pour l&rsquo;\u00e9tablissement, c&rsquo;est un temps qui permet d&rsquo;expliciter le r\u00f4le des d\u00e9l\u00e9gu\u00e9s, d&rsquo;informer sur la vie et le fonctionnement de l&rsquo;\u00e9tablissement, de favoriser le dialogue entre tous les acteurs de la vie scolaire \u00a0 Pour qui ? \u00c9coles, coll\u00e8ges, lyc\u00e9es. Instances Lyc\u00e9ennes : CVL, FSE, Maison de Lyc\u00e9ens, Conseils d&rsquo;Administration Objectifs La Ligue propose des modules de formation adapt\u00e9s aux besoins identifi\u00e9s par les \u00e9quipes \u00e9ducatives : Permettre aux d\u00e9l\u00e9gu\u00e9s de conna\u00eetre leurs devoirs et leurs droits afin de pouvoir les exercer D\u00e9velopper des capacit\u00e9s et des comp\u00e9tences \u00e0 la vie d\u00e9mocratique par l&rsquo;exp\u00e9rience de la participation et de la prise de responsabilit\u00e9 Pr\u00e9parer les d\u00e9l\u00e9gu\u00e9s \u00e0 l&rsquo;exercice de leur mandat d&rsquo;\u00e9lu, aux fonctions de repr\u00e9sentation, de communication et d&rsquo;animation Permettre \u00e0 l&rsquo;adulte d&rsquo;accompagner le d\u00e9l\u00e9gu\u00e9 \u00e9l\u00e8ve dans sa mission NOUS VOUS PROPOSONS : Rencontre et pr\u00e9paration avec vous de l&rsquo;intervention, des contenus et objectifs adapt\u00e9s au groupe d&rsquo;\u00e9l\u00e8ves. Intervention en petit groupe pour une formation allant de 2 journ\u00e9es jusqu&rsquo;\u00e0 des modules de trois jours au cours de l&rsquo;ann\u00e9e par un ou des formateurs FAL sp\u00e9cialement form\u00e9s pour intervenir aupr\u00e8s des scolaires. Apport p\u00e9dagogique Nous pouvons mobiliser notre \u00e9quipe p\u00e9dagogique tout au long de l&rsquo;ann\u00e9e avec des temps de formation sp\u00e9cifiques pour les enseignants en d\u00e9but d&rsquo;ann\u00e9e. Techniques et m\u00e9thodes p\u00e9dagogiques actives qui favorisent la prise de parole des jeunes (jeux, \u00e9changes, mises en situation&#8230;) Co\u00fbt de la formation : nous consulter Vous pouvez nous contacter pour vous en savoir plus sur nos propositions de de formation<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","h5ap_radio_sources":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-669","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves -\" \/>\n<meta property=\"og:description\" content=\"Nous consid\u00e9rons que former les d\u00e9l\u00e9gu\u00e9s \u00e9l\u00e8ves comporte un double enjeu citoyen dans les coll\u00e8ges et les lyc\u00e9es : Permettre aux d\u00e9l\u00e9gu\u00e9s d&rsquo;exercer au mieux leur fonction par une meilleure connaissance de leur \u00e9tablissement et de leur r\u00f4le Pour l&rsquo;\u00e9tablissement, c&rsquo;est un temps qui permet d&rsquo;expliciter le r\u00f4le des d\u00e9l\u00e9gu\u00e9s, d&rsquo;informer sur la vie et le fonctionnement de l&rsquo;\u00e9tablissement, de favoriser le dialogue entre tous les acteurs de la vie scolaire \u00a0 Pour qui ? \u00c9coles, coll\u00e8ges, lyc\u00e9es. Instances Lyc\u00e9ennes : CVL, FSE, Maison de Lyc\u00e9ens, Conseils d&rsquo;Administration Objectifs La Ligue propose des modules de formation adapt\u00e9s aux besoins identifi\u00e9s par les \u00e9quipes \u00e9ducatives : Permettre aux d\u00e9l\u00e9gu\u00e9s de conna\u00eetre leurs devoirs et leurs droits afin de pouvoir les exercer D\u00e9velopper des capacit\u00e9s et des comp\u00e9tences \u00e0 la vie d\u00e9mocratique par l&rsquo;exp\u00e9rience de la participation et de la prise de responsabilit\u00e9 Pr\u00e9parer les d\u00e9l\u00e9gu\u00e9s \u00e0 l&rsquo;exercice de leur mandat d&rsquo;\u00e9lu, aux fonctions de repr\u00e9sentation, de communication et d&rsquo;animation Permettre \u00e0 l&rsquo;adulte d&rsquo;accompagner le d\u00e9l\u00e9gu\u00e9 \u00e9l\u00e8ve dans sa mission NOUS VOUS PROPOSONS : Rencontre et pr\u00e9paration avec vous de l&rsquo;intervention, des contenus et objectifs adapt\u00e9s au groupe d&rsquo;\u00e9l\u00e8ves. Intervention en petit groupe pour une formation allant de 2 journ\u00e9es jusqu&rsquo;\u00e0 des modules de trois jours au cours de l&rsquo;ann\u00e9e par un ou des formateurs FAL sp\u00e9cialement form\u00e9s pour intervenir aupr\u00e8s des scolaires. Apport p\u00e9dagogique Nous pouvons mobiliser notre \u00e9quipe p\u00e9dagogique tout au long de l&rsquo;ann\u00e9e avec des temps de formation sp\u00e9cifiques pour les enseignants en d\u00e9but d&rsquo;ann\u00e9e. Techniques et m\u00e9thodes p\u00e9dagogiques actives qui favorisent la prise de parole des jeunes (jeux, \u00e9changes, mises en situation&#8230;) Co\u00fbt de la formation : nous consulter Vous pouvez nous contacter pour vous en savoir plus sur nos propositions de de formation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-05T08:17:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-13T10:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/dev.laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg\" \/>\n<meta name=\"author\" content=\"solene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"solene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/\"},\"author\":{\"name\":\"solene\",\"@id\":\"https:\\\/\\\/laligue53.org\\\/#\\\/schema\\\/person\\\/1abd68130308384db2389adc7e79a1c6\"},\"headline\":\"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves\",\"datePublished\":\"2018-06-05T08:17:38+00:00\",\"dateModified\":\"2018-06-13T10:16:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/\"},\"wordCount\":342,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dev.laligue53.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/delegue-300x225.jpg\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/\",\"url\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/\",\"name\":\"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/dev.laligue53.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/delegue-300x225.jpg\",\"datePublished\":\"2018-06-05T08:17:38+00:00\",\"dateModified\":\"2018-06-13T10:16:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/#\\\/schema\\\/person\\\/1abd68130308384db2389adc7e79a1c6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#primaryimage\",\"url\":\"http:\\\/\\\/dev.laligue53.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/delegue-300x225.jpg\",\"contentUrl\":\"http:\\\/\\\/dev.laligue53.org\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/delegue-300x225.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/2018\\\/06\\\/05\\\/formation-des-delegues-eleves\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/laligue53.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laligue53.org\\\/#website\",\"url\":\"https:\\\/\\\/laligue53.org\\\/\",\"name\":\"\",\"description\":\"S&#039;associer est une force\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laligue53.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laligue53.org\\\/#\\\/schema\\\/person\\\/1abd68130308384db2389adc7e79a1c6\",\"name\":\"solene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce2e419e3b64bb96366252f00df0bfe11c42c21b1bf0d6fb9556d823c367b289?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce2e419e3b64bb96366252f00df0bfe11c42c21b1bf0d6fb9556d823c367b289?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce2e419e3b64bb96366252f00df0bfe11c42c21b1bf0d6fb9556d823c367b289?s=96&d=mm&r=g\",\"caption\":\"solene\"},\"url\":\"https:\\\/\\\/laligue53.org\\\/index.php\\\/author\\\/solene\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/","og_locale":"fr_FR","og_type":"article","og_title":"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves -","og_description":"Nous consid\u00e9rons que former les d\u00e9l\u00e9gu\u00e9s \u00e9l\u00e8ves comporte un double enjeu citoyen dans les coll\u00e8ges et les lyc\u00e9es : Permettre aux d\u00e9l\u00e9gu\u00e9s d&rsquo;exercer au mieux leur fonction par une meilleure connaissance de leur \u00e9tablissement et de leur r\u00f4le Pour l&rsquo;\u00e9tablissement, c&rsquo;est un temps qui permet d&rsquo;expliciter le r\u00f4le des d\u00e9l\u00e9gu\u00e9s, d&rsquo;informer sur la vie et le fonctionnement de l&rsquo;\u00e9tablissement, de favoriser le dialogue entre tous les acteurs de la vie scolaire \u00a0 Pour qui ? \u00c9coles, coll\u00e8ges, lyc\u00e9es. Instances Lyc\u00e9ennes : CVL, FSE, Maison de Lyc\u00e9ens, Conseils d&rsquo;Administration Objectifs La Ligue propose des modules de formation adapt\u00e9s aux besoins identifi\u00e9s par les \u00e9quipes \u00e9ducatives : Permettre aux d\u00e9l\u00e9gu\u00e9s de conna\u00eetre leurs devoirs et leurs droits afin de pouvoir les exercer D\u00e9velopper des capacit\u00e9s et des comp\u00e9tences \u00e0 la vie d\u00e9mocratique par l&rsquo;exp\u00e9rience de la participation et de la prise de responsabilit\u00e9 Pr\u00e9parer les d\u00e9l\u00e9gu\u00e9s \u00e0 l&rsquo;exercice de leur mandat d&rsquo;\u00e9lu, aux fonctions de repr\u00e9sentation, de communication et d&rsquo;animation Permettre \u00e0 l&rsquo;adulte d&rsquo;accompagner le d\u00e9l\u00e9gu\u00e9 \u00e9l\u00e8ve dans sa mission NOUS VOUS PROPOSONS : Rencontre et pr\u00e9paration avec vous de l&rsquo;intervention, des contenus et objectifs adapt\u00e9s au groupe d&rsquo;\u00e9l\u00e8ves. Intervention en petit groupe pour une formation allant de 2 journ\u00e9es jusqu&rsquo;\u00e0 des modules de trois jours au cours de l&rsquo;ann\u00e9e par un ou des formateurs FAL sp\u00e9cialement form\u00e9s pour intervenir aupr\u00e8s des scolaires. Apport p\u00e9dagogique Nous pouvons mobiliser notre \u00e9quipe p\u00e9dagogique tout au long de l&rsquo;ann\u00e9e avec des temps de formation sp\u00e9cifiques pour les enseignants en d\u00e9but d&rsquo;ann\u00e9e. Techniques et m\u00e9thodes p\u00e9dagogiques actives qui favorisent la prise de parole des jeunes (jeux, \u00e9changes, mises en situation&#8230;) Co\u00fbt de la formation : nous consulter Vous pouvez nous contacter pour vous en savoir plus sur nos propositions de de formation","og_url":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/","article_published_time":"2018-06-05T08:17:38+00:00","article_modified_time":"2018-06-13T10:16:57+00:00","og_image":[{"url":"http:\/\/dev.laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg","type":"","width":"","height":""}],"author":"solene","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"solene","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#article","isPartOf":{"@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/"},"author":{"name":"solene","@id":"https:\/\/laligue53.org\/#\/schema\/person\/1abd68130308384db2389adc7e79a1c6"},"headline":"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves","datePublished":"2018-06-05T08:17:38+00:00","dateModified":"2018-06-13T10:16:57+00:00","mainEntityOfPage":{"@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/"},"wordCount":342,"commentCount":0,"image":{"@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/","url":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/","name":"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves -","isPartOf":{"@id":"https:\/\/laligue53.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#primaryimage"},"image":{"@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#primaryimage"},"thumbnailUrl":"http:\/\/dev.laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg","datePublished":"2018-06-05T08:17:38+00:00","dateModified":"2018-06-13T10:16:57+00:00","author":{"@id":"https:\/\/laligue53.org\/#\/schema\/person\/1abd68130308384db2389adc7e79a1c6"},"breadcrumb":{"@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#primaryimage","url":"http:\/\/dev.laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg","contentUrl":"http:\/\/dev.laligue53.org\/wp-content\/uploads\/2018\/06\/delegue-300x225.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/laligue53.org\/index.php\/2018\/06\/05\/formation-des-delegues-eleves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/laligue53.org\/"},{"@type":"ListItem","position":2,"name":"Formation des d\u00e9l\u00e9gu\u00e9s-\u00e9l\u00e8ves"}]},{"@type":"WebSite","@id":"https:\/\/laligue53.org\/#website","url":"https:\/\/laligue53.org\/","name":"","description":"S&#039;associer est une force","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laligue53.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/laligue53.org\/#\/schema\/person\/1abd68130308384db2389adc7e79a1c6","name":"solene","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ce2e419e3b64bb96366252f00df0bfe11c42c21b1bf0d6fb9556d823c367b289?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ce2e419e3b64bb96366252f00df0bfe11c42c21b1bf0d6fb9556d823c367b289?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ce2e419e3b64bb96366252f00df0bfe11c42c21b1bf0d6fb9556d823c367b289?s=96&d=mm&r=g","caption":"solene"},"url":"https:\/\/laligue53.org\/index.php\/author\/solene\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"solene","author_link":"https:\/\/laligue53.org\/index.php\/author\/solene\/"},"uagb_comment_info":20,"uagb_excerpt":"Nous consid\u00e9rons que former les d\u00e9l\u00e9gu\u00e9s \u00e9l\u00e8ves comporte un double enjeu citoyen dans les coll\u00e8ges et les lyc\u00e9es : Permettre aux d\u00e9l\u00e9gu\u00e9s d&rsquo;exercer au mieux leur fonction par une meilleure connaissance de leur \u00e9tablissement et de leur r\u00f4le Pour l&rsquo;\u00e9tablissement, c&rsquo;est un temps qui permet d&rsquo;expliciter le r\u00f4le des d\u00e9l\u00e9gu\u00e9s, d&rsquo;informer sur la vie et\u2026","_links":{"self":[{"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/posts\/669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/comments?post=669"}],"version-history":[{"count":6,"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/posts\/669\/revisions"}],"predecessor-version":[{"id":1826,"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/posts\/669\/revisions\/1826"}],"wp:attachment":[{"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/media?parent=669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/categories?post=669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laligue53.org\/index.php\/wp-json\/wp\/v2\/tags?post=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}